{"id":27420,"date":"2026-01-21T17:01:34","date_gmt":"2026-01-21T16:01:34","guid":{"rendered":"https:\/\/sportnautic.com\/?page_id=27420"},"modified":"2026-06-01T12:47:36","modified_gmt":"2026-06-01T10:47:36","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/sportnautic.com\/en\/politica-de-privacidad\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"27420\" class=\"elementor elementor-27420\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc0979b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc0979b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10be183\" data-id=\"10be183\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43a1c95 elementor-widget elementor-widget-spacer\" data-id=\"43a1c95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6509ce9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6509ce9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-951cf7b\" data-id=\"951cf7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8de1214 elementor-widget elementor-widget-heading\" data-id=\"8de1214\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Pol\u00edtica de Privacidad<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fb9abf elementor-widget elementor-widget-spacer\" data-id=\"0fb9abf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05ea382 elementor-widget elementor-widget-text-editor\" data-id=\"05ea382\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><span class=\"s1\"><b>Responsible for the treatment<\/b><\/span><\/h2><p class=\"p2\">El responsable del tratamiento de los datos personales es <span class=\"s1\"><b>SPORT NAUTIC<\/b><\/span>, operada por <span class=\"s1\"><b>Roga N\u00e1utica SL<\/b><\/span>, con CIF B0697083 y domicilio en Av. Joan Fuster n\u00ba 2, Local 1, D\u00e9nia (Alicante).<br \/>Correo de contacto: denia@sportnautic.com<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5b6354 elementor-widget elementor-widget-text-editor\" data-id=\"c5b6354\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><span class=\"s1\"><b>Data that is collected<\/b><\/span><\/h2><p class=\"p2\">A trav\u00e9s de formularios de contacto y herramientas de an\u00e1lisis, podemos recoger los siguientes datos personales:<\/p><ul><li class=\"p2\">Name and surname<\/li><li class=\"p2\">Direcci\u00f3n de correo electr\u00f3nico<\/li><li>N\u00famero de tel\u00e9fono<\/li><li>Direcci\u00f3n IP<\/li><li>Datos derivados de la navegaci\u00f3n en la web (cookies anal\u00edticas)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8be9fb2 elementor-widget elementor-widget-text-editor\" data-id=\"8be9fb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><span class=\"s1\"><b>Purpose of treatment<\/b><\/span><\/h2><p class=\"p2\">Los datos personales se utilizan con las siguientes finalidades:<\/p><ul><li>Gestionar consultas, solicitudes de informaci\u00f3n y contacto comercial.<\/li><li>Atender solicitudes relacionadas con embarcaciones nuevas o de ocasi\u00f3n.<\/li><li>Enviar comunicaciones comerciales, promociones y novedades del sector n\u00e1utico (si el usuario ha dado su consentimiento).<\/li><li>Analizar el tr\u00e1fico y comportamiento de navegaci\u00f3n en la web para mejorar la experiencia del usuario.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d98356e elementor-widget elementor-widget-text-editor\" data-id=\"d98356e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><span class=\"s1\"><b>Conservaci\u00f3n de los datos<\/b><\/span><\/h2><p class=\"p2\">Los datos se conservar\u00e1n durante el tiempo necesario para cumplir la finalidad para la que fueron recogidos.<\/p><p class=\"p3\">En el caso de comunicaciones comerciales, los datos se mantendr\u00e1n mientras el usuario no solicite su supresi\u00f3n o revoque su consentimiento.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-400ad81 elementor-widget elementor-widget-text-editor\" data-id=\"400ad81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><span class=\"s1\"><b>Cesi\u00f3n de datos a terceros<\/b><\/span><\/h2><p class=\"p2\">No se ceder\u00e1n datos personales a terceros, salvo obligaci\u00f3n legal o requerimiento de autoridades competentes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a99e31 elementor-widget elementor-widget-text-editor\" data-id=\"9a99e31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><span class=\"s1\"><b>Security measures<\/b><\/span><\/h2><p class=\"p2\">SPORT NAUTIC adopta las medidas t\u00e9cnicas y organizativas necesarias para garantizar la seguridad, integridad y confidencialidad de los datos personales, evitando su p\u00e9rdida, alteraci\u00f3n o acceso no autorizado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99f8d21 elementor-widget elementor-widget-text-editor\" data-id=\"99f8d21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><span class=\"s1\"><b>User rights<\/b><\/span><\/h2><p class=\"p2\">El usuario puede ejercer en cualquier momento sus derechos de:<\/p><ul><li>Acceso<\/li><li>Rectificaci\u00f3n<\/li><li>Supresi\u00f3n<\/li><li>Oposici\u00f3n<\/li><li>Limitaci\u00f3n del tratamiento<\/li><li>Portabilidad de los datos<\/li><\/ul><p class=\"p3\">Para ejercer estos derechos, puede enviar una solicitud a: <span class=\"s1\"><b>denia@sportnautic.com<\/b><\/span>, adjuntando una copia de su documento de identidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba9b8af elementor-widget elementor-widget-text-editor\" data-id=\"ba9b8af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><span class=\"s1\"><b>User rights<\/b><\/span><\/h2><p class=\"p2\">El usuario puede ejercer en cualquier momento sus derechos de:<\/p><ul><li>Acceso<\/li><li>Rectificaci\u00f3n<\/li><li>Supresi\u00f3n<\/li><li>Oposici\u00f3n<\/li><li>Limitaci\u00f3n del tratamiento<\/li><li>Portabilidad de los datos<\/li><\/ul><p class=\"p3\">Para ejercer estos derechos, puede enviar una solicitud a: <span class=\"s1\"><b>denia@sportnautic.com<\/b><\/span>, adjuntando una copia de su documento de identidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c84dabf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c84dabf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15841aa\" data-id=\"15841aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de Privacidad Responsable del tratamiento El responsable del tratamiento de los datos personales es SPORT NAUTIC, operada por Roga N\u00e1utica SL, con CIF B0697083 y domicilio en Av. Joan Fuster n\u00ba 2, Local 1, D\u00e9nia (Alicante).Correo de contacto: denia@sportnautic.com Datos que se recogen A trav\u00e9s de formularios de contacto y herramientas de an\u00e1lisis, podemos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-27420","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pol\u00edtica de privacidad | SPORT NAUTIC<\/title>\n<meta name=\"description\" content=\"Revisa nuestra Pol\u00edtica de privacidad para saber c\u00f3mo utilizamos tus datos personales y mejorar tu experiencia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sportnautic.com\/en\/politica-de-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barcos en venta y alquiler | SPORT NAUTIC\" \/>\n<meta property=\"og:description\" content=\"Distribuidor oficial y expertos en el mar. Barcos nuevos y de ocasi\u00f3n listos para navegar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sportnautic.com\/en\/politica-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"SPORT NAUTIC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sportnautic\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T10:47:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sportnautic.com\/wp-content\/uploads\/2026\/03\/Gran-Turismo-50_5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1079\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sportnautic.com\\\/politica-de-privacidad\\\/\",\"url\":\"https:\\\/\\\/sportnautic.com\\\/politica-de-privacidad\\\/\",\"name\":\"Pol\u00edtica de privacidad | SPORT NAUTIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sportnautic.com\\\/#website\"},\"datePublished\":\"2026-01-21T16:01:34+00:00\",\"dateModified\":\"2026-06-01T10:47:36+00:00\",\"description\":\"Revisa nuestra Pol\u00edtica de privacidad para saber c\u00f3mo utilizamos tus datos personales y mejorar tu experiencia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sportnautic.com\\\/politica-de-privacidad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sportnautic.com\\\/politica-de-privacidad\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sportnautic.com\\\/politica-de-privacidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sportnautic.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politica de privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sportnautic.com\\\/#website\",\"url\":\"https:\\\/\\\/sportnautic.com\\\/\",\"name\":\"SPORT NAUTIC\",\"description\":\"Distribuidor oficial Beneteau, Excess y Wellcraft\",\"publisher\":{\"@id\":\"https:\\\/\\\/sportnautic.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sportnautic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sportnautic.com\\\/#organization\",\"name\":\"SPORT NAUTIC\",\"url\":\"https:\\\/\\\/sportnautic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sportnautic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sportnautic.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-LOGO-REDONDO-SPORTNAUTIC-FLOTA-2-2.png\",\"contentUrl\":\"https:\\\/\\\/sportnautic.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-LOGO-REDONDO-SPORTNAUTIC-FLOTA-2-2.png\",\"width\":512,\"height\":512,\"caption\":\"SPORT NAUTIC\"},\"image\":{\"@id\":\"https:\\\/\\\/sportnautic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sportnautic\",\"https:\\\/\\\/instagram.com\\\/sportnautic\"],\"description\":\"SPORT NAUTIC es una empresa especializada en la venta y alquiler de embarcaciones en la Comunidad Valenciana y Murcia. Ofrece barcos nuevos y de ocasi\u00f3n, servicio t\u00e9cnico y asesoramiento personalizado. Distribuidor oficial de marcas n\u00e1uticas y referente en el sector en la Comunidad Valenciana y Murcia.\",\"email\":\"info@sportnautic.com\",\"telephone\":\"+34 96 578 43 20\",\"legalName\":\"Roga Nautica S.L.\",\"foundingDate\":\"1989-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de privacidad | SPORT NAUTIC","description":"Revisa nuestra Pol\u00edtica de privacidad para saber c\u00f3mo utilizamos tus datos personales y mejorar tu experiencia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sportnautic.com\/en\/politica-de-privacidad\/","og_locale":"en_US","og_type":"article","og_title":"Barcos en venta y alquiler | SPORT NAUTIC","og_description":"Distribuidor oficial y expertos en el mar. Barcos nuevos y de ocasi\u00f3n listos para navegar.","og_url":"https:\/\/sportnautic.com\/en\/politica-de-privacidad\/","og_site_name":"SPORT NAUTIC","article_publisher":"https:\/\/facebook.com\/sportnautic","article_modified_time":"2026-06-01T10:47:36+00:00","og_image":[{"width":1920,"height":1079,"url":"https:\/\/sportnautic.com\/wp-content\/uploads\/2026\/03\/Gran-Turismo-50_5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sportnautic.com\/politica-de-privacidad\/","url":"https:\/\/sportnautic.com\/politica-de-privacidad\/","name":"Pol\u00edtica de privacidad | SPORT NAUTIC","isPartOf":{"@id":"https:\/\/sportnautic.com\/#website"},"datePublished":"2026-01-21T16:01:34+00:00","dateModified":"2026-06-01T10:47:36+00:00","description":"Revisa nuestra Pol\u00edtica de privacidad para saber c\u00f3mo utilizamos tus datos personales y mejorar tu experiencia.","breadcrumb":{"@id":"https:\/\/sportnautic.com\/politica-de-privacidad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sportnautic.com\/politica-de-privacidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sportnautic.com\/politica-de-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sportnautic.com\/"},{"@type":"ListItem","position":2,"name":"Politica de privacidad"}]},{"@type":"WebSite","@id":"https:\/\/sportnautic.com\/#website","url":"https:\/\/sportnautic.com\/","name":"SPORT NAUTIC","description":"Distribuidor oficial Beneteau, Excess y Wellcraft","publisher":{"@id":"https:\/\/sportnautic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sportnautic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sportnautic.com\/#organization","name":"SPORT NAUTIC","url":"https:\/\/sportnautic.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sportnautic.com\/#\/schema\/logo\/image\/","url":"https:\/\/sportnautic.com\/wp-content\/uploads\/2025\/11\/cropped-LOGO-REDONDO-SPORTNAUTIC-FLOTA-2-2.png","contentUrl":"https:\/\/sportnautic.com\/wp-content\/uploads\/2025\/11\/cropped-LOGO-REDONDO-SPORTNAUTIC-FLOTA-2-2.png","width":512,"height":512,"caption":"SPORT NAUTIC"},"image":{"@id":"https:\/\/sportnautic.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sportnautic","https:\/\/instagram.com\/sportnautic"],"description":"SPORT NAUTIC is a company specialized in the sale and rental of boats in the Valencian Community and Murcia. They offer new and used boats, technical service, and personalized advice. They are an official distributor of nautical brands and a leader in the sector in the Valencian Community and Murcia.","email":"info@sportnautic.com","telephone":"+34 96 578 43 20","legalName":"Roga Nautica S.L.","foundingDate":"1989-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/sportnautic.com\/en\/wp-json\/wp\/v2\/pages\/27420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sportnautic.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sportnautic.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sportnautic.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sportnautic.com\/en\/wp-json\/wp\/v2\/comments?post=27420"}],"version-history":[{"count":10,"href":"https:\/\/sportnautic.com\/en\/wp-json\/wp\/v2\/pages\/27420\/revisions"}],"predecessor-version":[{"id":29820,"href":"https:\/\/sportnautic.com\/en\/wp-json\/wp\/v2\/pages\/27420\/revisions\/29820"}],"wp:attachment":[{"href":"https:\/\/sportnautic.com\/en\/wp-json\/wp\/v2\/media?parent=27420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}